{"id":22944,"date":"2025-11-26T08:39:42","date_gmt":"2025-11-26T11:39:42","guid":{"rendered":"https:\/\/tigredigital.com.ar\/noticias\/?p=22944"},"modified":"2025-11-26T08:39:43","modified_gmt":"2025-11-26T11:39:43","slug":"camaras-dos-sujetos-detenidos-en-benavidez-luego-de-robar-una-moto","status":"publish","type":"post","link":"https:\/\/tigredigital.com.ar\/noticias\/camaras-dos-sujetos-detenidos-en-benavidez-luego-de-robar-una-moto\/","title":{"rendered":"C\u00e1maras: dos sujetos detenidos en Benav\u00eddez luego de robar una moto"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\" id=\"m_4801949093920922753isPasted\"><strong>Dos malvivientes quedaron a disposici\u00f3n de la Justicia luego de un operativo coordinado con efectivos de la Polic\u00eda de Buenos Aires. El sistema de videovigilancia del Centro de Operaciones Tigre fue clave en la detecci\u00f3n de los sujetos y el esclarecimiento del il\u00edcito que ocurri\u00f3 en Benav\u00eddez<\/strong><\/p>\n\n\n\n<!--more-->\n<!--noteaser-->\n\n\n\n<p class=\"wp-block-paragraph\" id=\"m_4801949093920922753isPasted\">Dos sospechosos fueron detenidos por el Centro de Operaciones Tigre (COT) luego de robar una moto que se encontraba estacionada en Benav\u00eddez. Quedaron a disposici\u00f3n de la Justicia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"C\u00e1maras: dos sujetos detenidos en Benav\u00eddez luego de robar una moto\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/zGxgekpuy6U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hecho sucedi\u00f3 en horas de la tarde cuando los agentes del COT detectaron que dos individuos con actitud sospechosa trasladaban el veh\u00edculo a tiro. Luego de un trabajo minucioso a trav\u00e9s de la central de monitoreo, visualizaron que el rodado hab\u00eda sido robado en la intersecci\u00f3n de las calles Alvear y Brasil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mediante un seguimiento f\u00edlmico, los efectivos del COT y de la Polic\u00eda de la Provincia de Buenos Aires interceptaron a los delincuentes en el cruce de las arterias Chile y Conesa, donde los identificaron, detuvieron y trasladaron a comisar\u00eda.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-jetpack-related-posts\">\n<h4 class=\"wp-block-heading\">Noticias relacionadas<\/h4>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">M\u00e1s noticias<\/h4>\n\n\n<ul class=\"wp-block-latest-posts__list is-grid columns-2 has-author aligncenter wp-block-latest-posts\"><li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/benavidez-detencion-narcomenudeo-operativo-cot\/\" aria-label=\"Detuvieron a dos personas por comercializar drogas en Benav\u00eddez\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"295\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot8-1024x576.png\" class=\"attachment-large size-large wp-post-image\" alt=\"Dispositivo de seguridad y patrullas del COT interviniendo en la detenci\u00f3n de los implicados en Benav\u00eddez\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot8-1024x576.png 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot8-300x169.png 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot8-768x432.png 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot8.png 1280w\" sizes=\"auto, 100vw\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/benavidez-detencion-narcomenudeo-operativo-cot\/\">Detuvieron a dos personas por comercializar drogas en Benav\u00eddez<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/rincon-de-milberg-jardin-950-entrega-material-ludico\/\" aria-label=\"El Municipio entreg\u00f3 nuevos kits did\u00e1cticos en el Jard\u00edn N\u00b0950 de Rinc\u00f3n de Milberg\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-11-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Integrantes del equipo educativo y autoridades locales durante la presentaci\u00f3n de los nuevos kits de juego en el Jard\u00edn N\u00b0950 de Rinc\u00f3n de Milberg\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-11-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-11-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-11-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-11.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/rincon-de-milberg-jardin-950-entrega-material-ludico\/\">El Municipio entreg\u00f3 nuevos kits did\u00e1cticos en el Jard\u00edn N\u00b0950 de Rinc\u00f3n de Milberg<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/inauguracion-nuevos-vestuarios-polideportivo-delfo-cabrera-el-talar\/\" aria-label=\"El Talar: quedaron inaugurados los vestuarios del Polideportivo municipal Delfo Cabrera\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot1-1-1024x597.png\" class=\"attachment-large size-large wp-post-image\" alt=\"Se construyeron dos vestuarios principales para hombres y mujeres. Incluye cambiadores para ni\u00f1os pensados para actividades infantiles, ba\u00f1os para personas con discapacidad, sectores de apoyo y un sector para revisiones m\u00e9dicas\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot1-1-1024x597.png 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot1-1-300x175.png 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot1-1-768x448.png 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot1-1.png 1200w\" sizes=\"auto, 100vw\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/inauguracion-nuevos-vestuarios-polideportivo-delfo-cabrera-el-talar\/\">El Talar: quedaron inaugurados los vestuarios del Polideportivo municipal Delfo Cabrera<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/entrega-certificados-emprendedoras-rodantes-tigre\/\" aria-label=\"M\u00e1s de 100 vecinas de Tigre recibieron sus certificados del programa Emprendedoras Rodantes\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-4-3-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Vecinas de Tigre exhiben sus diplomas de finalizaci\u00f3n de talleres junto a sus kits de trabajo en el Centro Universitario\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-4-3-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-4-3-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-4-3-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-4-3.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/entrega-certificados-emprendedoras-rodantes-tigre\/\">M\u00e1s de 100 vecinas de Tigre recibieron sus certificados del programa Emprendedoras Rodantes<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/puesta-valor-polideportivo-tercera-edad-rincon-milberg\/\" aria-label=\"Finalizaron obras de infraestructura en el predio para la tercera edad Ecosol\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-3-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Adultos mayores celebraron el 9 de Julio en las instalaciones renovadas del polideportivo municipal\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-3-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-3-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-3-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-3.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/puesta-valor-polideportivo-tercera-edad-rincon-milberg\/\">Finalizaron obras de infraestructura en el predio para la tercera edad Ecosol<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/siniestro-vial-auto-moto-benavidez-camino-bota\/\" aria-label=\"Maniobra imprudente en Benav\u00eddez provoca violento choque\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"295\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot10.png\" class=\"attachment-large size-large wp-post-image\" alt=\"El choque ocurri\u00f3 a primera hora de la ma\u00f1ana, cuando el rodado de mayor porte colision\u00f3 de frente al motoveh\u00edculo que circulaba por Colectora Este -en sentido opuesto- y su intersecci\u00f3n con Camino de la Bota. Al detectar lo ocurrido a trav\u00e9s de las c\u00e1maras, los operadores de la central dieron aviso al m\u00f3vil m\u00e1s cercano.\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot10.png 640w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot10-300x169.png 300w\" sizes=\"auto, 100vw\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/siniestro-vial-auto-moto-benavidez-camino-bota\/\">Maniobra imprudente en Benav\u00eddez provoca violento choque<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/agenda-actividades-gratuitas-vacaciones-invierno-tigre\/\" aria-label=\"El Municipio de Tigre present\u00f3 sus propuestas culturales gratuitas para las vacaciones de invierno\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-6-1-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Con m\u00e1s de 70 propuestas culturales para las vacaciones de invierno, el Municipio ofrecer\u00e1 una amplia agenda gratuita de espect\u00e1culos, teatro, cine\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-6-1-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-6-1-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-6-1-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-6-1.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/agenda-actividades-gratuitas-vacaciones-invierno-tigre\/\">El Municipio de Tigre present\u00f3 sus propuestas culturales gratuitas para las vacaciones de invierno<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/vecinos-troncos-talar-celebraron-dia-independencia\/\" aria-label=\"La comunidad de Troncos del Talar celebr\u00f3 el 9 de Julio junto a autoridades municipales\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-2-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"El intendente Julio Zamora particip\u00f3 del encuentro con la comunidad en la Asociaci\u00f3n Junta Vecinal.\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-2-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-2-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-2-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-2.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/vecinos-troncos-talar-celebraron-dia-independencia\/\">La comunidad de Troncos del Talar celebr\u00f3 el 9 de Julio junto a autoridades municipales<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/entrega-anteojos-programa-para-verte-mejor-tigre\/\" aria-label=\"\u00abPara Verte Mejor\u00bb alcanz\u00f3 los 500 pares de anteojos entregados a estudiantes durante el primer semestre\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-7-1-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"La secretaria de Educaci\u00f3n y Promoci\u00f3n Social, Gisela Zamora, particip\u00f3 de una nueva jornada del programa municipal de salud visual\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-7-1-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-7-1-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-7-1-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-7-1.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/entrega-anteojos-programa-para-verte-mejor-tigre\/\">\u00abPara Verte Mejor\u00bb alcanz\u00f3 los 500 pares de anteojos entregados a estudiantes durante el primer semestre<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/talleres-orientacion-vocacional-centro-universitario-tigre\/\" aria-label=\"Estudiantes secundarios participaron de una nueva jornada de orientaci\u00f3n vocacional en el CUT\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-1-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"El Municipio llev\u00f3 a cabo una nueva jornada del Taller de Orientaci\u00f3n Vocacional en el Centro Universitario Tigre (CUT). Los estudiantes de sexto a\u00f1o de secundaria participaron de una recorrida por el espacio y se presentaron las ofertas acad\u00e9micas locales\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-1-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-1-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-1-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-1.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/talleres-orientacion-vocacional-centro-universitario-tigre\/\">Estudiantes secundarios participaron de una nueva jornada de orientaci\u00f3n vocacional en el CUT<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<\/ul>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-cover is-light\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"500\" class=\"wp-block-cover__image-background wp-image-18331\" alt=\"\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2023\/11\/LOGO-TIGRE-DIGITAL-CIRCULO.png\" data-object-fit=\"cover\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2023\/11\/LOGO-TIGRE-DIGITAL-CIRCULO.png 480w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2023\/11\/LOGO-TIGRE-DIGITAL-CIRCULO-288x300.png 288w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-group alignfull has-background-color has-white-color has-black-background-color has-text-color has-background has-link-color wp-elements-37ea6134c40452122b721bb912a37805\" style=\"min-height:40vh;margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--60);padding-right:var(--wp--preset--spacing--40);padding-bottom:var(--wp--preset--spacing--60);padding-left:var(--wp--preset--spacing--40)\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-container-core-group-is-layout-73ba516b wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns alignwide has-small-font-size is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center wp-block-paragraph\">(1648) Tigre<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Buenos Aires<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Argentina<\/p>\n\n\n\n<div style=\"height:24px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-stretch is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center wp-block-paragraph\">Comunicate con nosotros:<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><a href=\"contacto@tigredigital.com.ar\" target=\"_blank\" rel=\"noreferrer noopener\">contacto@tigredigital.com.ar<\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"500\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2023\/11\/LOGO-TIGRE-DIGITAL-CIRCULO-1.png\" alt=\"\" class=\"wp-image-18332\" style=\"width:98px;height:auto\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2023\/11\/LOGO-TIGRE-DIGITAL-CIRCULO-1.png 480w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2023\/11\/LOGO-TIGRE-DIGITAL-CIRCULO-1-288x300.png 288w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/figure>\n<\/div>\n\n\n<div style=\"height:24px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center wp-block-paragraph\">Adem\u00e1s pod\u00e9s  seguirnos en<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">nuestras redes sociales:<\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-center is-layout-flex wp-container-core-group-is-layout-35affd85 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/tigredigital\/\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.instagram.com\/tigredigitalnoticias\/\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/twitter.com\/digital_tigre\" target=\"_blank\" rel=\"noreferrer noopener\">Twitter<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.youtube.com\/channel\/UC26DeuIB96yC2vbePmuFH5A\" target=\"_blank\" rel=\"noreferrer noopener\">Youtube<\/a><\/p>\n<\/div>\n\n\n\n<div style=\"height:24px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center has-small-font-size wp-block-paragraph\">Proudly powered by <a href=\"https:\/\/wordpress.org\" rel=\"nofollow noopener\" target=\"_blank\">WordPress<\/a> <\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dos sospechosos fueron detenidos por el Centro de Operaciones Tigre (COT) luego de robar una moto que se encontraba estacionada en Benav\u00eddez. Quedaron a disposici\u00f3n de la Justicia<\/p>\n","protected":false},"author":2,"featured_media":22945,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[13],"tags":[135,68,71,65],"class_list":["post-22944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales","tag-benavidez-2","tag-cot","tag-policiales","tag-tigre"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/11\/unnamed-17.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":17387,"url":"https:\/\/tigredigital.com.ar\/noticias\/las-camaras-de-videovigilancia-captaron-a-dos-jovenes-robando-una-moto-fueron-detenidos-por-el-cot\/","url_meta":{"origin":22944,"position":0},"title":"Las c\u00e1maras de videovigilancia de Tigre captaron a dos j\u00f3venes robando una moto: fueron detenidos por el COT","author":"Daniel Lowy","date":"24 mayo, 2023","format":false,"excerpt":"Agentes del Centro de Operaciones Tigre (COT) detuvieron en Benav\u00eddez a dos j\u00f3venes que hurtaron una motocicleta estacionada en la vereda. Fue posible gracias a las c\u00e1maras de videovigilancia del distrito, que captaron el suceso","rel":"","context":"En \u00abPoliciales\u00bb","block_context":{"text":"Policiales","link":"https:\/\/tigredigital.com.ar\/noticias\/category\/policiales\/"},"img":{"alt_text":"Momento en que dos j\u00f3venes roban una motocicleta en Benavidez","src":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2023\/05\/077f5eeb8cdbb0cc2b294190e3ea71e8f1a5699e46d5b5767fb8c5d79eece2b7.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2023\/05\/077f5eeb8cdbb0cc2b294190e3ea71e8f1a5699e46d5b5767fb8c5d79eece2b7.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2023\/05\/077f5eeb8cdbb0cc2b294190e3ea71e8f1a5699e46d5b5767fb8c5d79eece2b7.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2023\/05\/077f5eeb8cdbb0cc2b294190e3ea71e8f1a5699e46d5b5767fb8c5d79eece2b7.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2023\/05\/077f5eeb8cdbb0cc2b294190e3ea71e8f1a5699e46d5b5767fb8c5d79eece2b7.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2023\/05\/077f5eeb8cdbb0cc2b294190e3ea71e8f1a5699e46d5b5767fb8c5d79eece2b7.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":22926,"url":"https:\/\/tigredigital.com.ar\/noticias\/un-sujeto-fue-detenido-en-benavidez-circulando-con-una-moto-robada\/","url_meta":{"origin":22944,"position":1},"title":"Un sujeto fue detenido en Benav\u00eddez circulando con una moto robada","author":"Daniel Lowy","date":"22 noviembre, 2025","format":false,"excerpt":"Las c\u00e1maras municipales del Centro de Operaciones Tigre detectaron a un sujeto con una moto sin patentes e inmediatamente los agentes de patrulla procedieron a detenerlo para su identificaci\u00f3n. Se constat\u00f3 que el veh\u00edculo era robado por lo que fue entregado a la justicia","rel":"","context":"En \u00abCOT\u00bb","block_context":{"text":"COT","link":"https:\/\/tigredigital.com.ar\/noticias\/category\/cot\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/11\/snapshot-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/11\/snapshot-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/11\/snapshot-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/11\/snapshot-1.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/11\/snapshot-1.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/11\/snapshot-1.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":23555,"url":"https:\/\/tigredigital.com.ar\/noticias\/benavidez-persecucion-cot-detenidos-moto\/","url_meta":{"origin":22944,"position":2},"title":"Benav\u00eddez: Tras intensa persecuci\u00f3n, el COT detuvo a dos sospechosos en moto","author":"Daniel Lowy","date":"4 marzo, 2026","format":false,"excerpt":"En una r\u00e1pida intervenci\u00f3n coordinada, el Centro de Operaciones Tigre (COT) logr\u00f3 la aprehensi\u00f3n de dos hombres que intentaron eludir un control de seguridad en la localidad de Benav\u00eddez. El incidente, que incluy\u00f3 una intensa persecuci\u00f3n por las calles del barrio, culmin\u00f3 con los sospechosos a disposici\u00f3n de la justicia.","rel":"","context":"En \u00abPoliciales\u00bb","block_context":{"text":"Policiales","link":"https:\/\/tigredigital.com.ar\/noticias\/category\/policiales\/"},"img":{"alt_text":"Dos hombres fueron detenidos en Benav\u00eddez tras una persecuci\u00f3n detectada por las c\u00e1maras del COT","src":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/03\/EL-COT-DETIENE-MOTOCICLISTAS-TRAS-PERSECUSION.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/03\/EL-COT-DETIENE-MOTOCICLISTAS-TRAS-PERSECUSION.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/03\/EL-COT-DETIENE-MOTOCICLISTAS-TRAS-PERSECUSION.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/03\/EL-COT-DETIENE-MOTOCICLISTAS-TRAS-PERSECUSION.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/03\/EL-COT-DETIENE-MOTOCICLISTAS-TRAS-PERSECUSION.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":22542,"url":"https:\/\/tigredigital.com.ar\/noticias\/un-sujeto-que-robo-una-moto-en-el-talar-fue-detenido-gracias-al-seguimiento-por-las-camaras\/","url_meta":{"origin":22944,"position":3},"title":"Un sujeto que rob\u00f3 una moto en El Talar fue detenido gracias al seguimiento por las c\u00e1maras","author":"Daniel Lowy","date":"3 septiembre, 2025","format":false,"excerpt":"En el El Talar, un sujeto fue detenido por el Centro de Operaciones Tigre (COT) luego de robar una motocicleta. Las c\u00e1maras municipales tuvieron un papel fundamental en seguimiento de la fuga: el individuo qued\u00f3 a disposici\u00f3n de la Justicia.","rel":"","context":"En \u00abC\u00e1maras\u00bb","block_context":{"text":"C\u00e1maras","link":"https:\/\/tigredigital.com.ar\/noticias\/category\/camaras\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/09\/snapshot2.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/09\/snapshot2.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/09\/snapshot2.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/09\/snapshot2.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/09\/snapshot2.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":22220,"url":"https:\/\/tigredigital.com.ar\/noticias\/en-benavidez-rompio-el-vidrio-de-un-automovil-para-robar-elementos-de-su-interior-fue-detenido\/","url_meta":{"origin":22944,"position":4},"title":"En Benav\u00eddez: rompi\u00f3 el vidrio de un autom\u00f3vil para robar elementos de su interior. Fue detenido","author":"Daniel Lowy","date":"19 julio, 2025","format":false,"excerpt":"Un hombre qued\u00f3 detenido luego de que intentara robar pertenencias de un veh\u00edculo en la localidad de Benav\u00eddez. El operativo se ejecut\u00f3 -luego de la denuncia de una vecina- de manera articulada con agentes del COT y efectivos de la Polic\u00eda de la Provincia de Buenos Aires.","rel":"","context":"En \u00abCOT\u00bb","block_context":{"text":"COT","link":"https:\/\/tigredigital.com.ar\/noticias\/category\/cot\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/07\/snapshot3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/07\/snapshot3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/07\/snapshot3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/07\/snapshot3.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/07\/snapshot3.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":21513,"url":"https:\/\/tigredigital.com.ar\/noticias\/quiso-huir-del-cot-en-una-moto-robada-y-con-dos-menores-a-bordo-perdio-el-control-y-cayeron-sobre-la-vereda\/","url_meta":{"origin":22944,"position":5},"title":"Quiso huir del COT en una moto robada y con dos menores a bordo: perdi\u00f3 el control y cayeron sobre la vereda","author":"Daniel Lowy","date":"16 abril, 2025","format":false,"excerpt":"Quiso huir del COT en una moto robada y con dos menores a bordo: perdi\u00f3 el control y cayeron sobre la vereda En la localidad de Benav\u00eddez, la sospechosa fue observada por las c\u00e1maras del Centro de Operaciones Tigre (COT) circulando en una moto con dos chicos a bordo. Alertados,\u2026","rel":"","context":"En \u00abC\u00e1maras\u00bb","block_context":{"text":"C\u00e1maras","link":"https:\/\/tigredigital.com.ar\/noticias\/category\/camaras\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/04\/snapshot1-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/04\/snapshot1-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/04\/snapshot1-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/04\/snapshot1-1.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/04\/snapshot1-1.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/04\/snapshot1-1.png?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/22944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=22944"}],"version-history":[{"count":1,"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/22944\/revisions"}],"predecessor-version":[{"id":22946,"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/22944\/revisions\/22946"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/22945"}],"wp:attachment":[{"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=22944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=22944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=22944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}