{"id":21276,"date":"2025-03-13T16:02:42","date_gmt":"2025-03-13T19:02:42","guid":{"rendered":"https:\/\/tigredigital.com.ar\/noticias\/?p=21276"},"modified":"2025-03-13T17:52:26","modified_gmt":"2025-03-13T20:52:26","slug":"el-tren-de-la-costa-tiene-nuevo-horario-nocturno","status":"publish","type":"post","link":"https:\/\/tigredigital.com.ar\/noticias\/el-tren-de-la-costa-tiene-nuevo-horario-nocturno\/","title":{"rendered":"El Tren de la Costa tiene nuevo horario nocturno"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>El ramal de la l\u00ednea Mitre que une la estaci\u00f3n Maip\u00fa, frente a la Quinta Presidencial, con la estaci\u00f3n Delta, pegada al casino tigrense, dispone de un nuevo cronograma de horarios<\/strong><\/p>\n\n\n\n<!--more-->\n<!--noteaser-->\n\n\n\n<p class=\"wp-block-paragraph\">A partir de esta semana, la empresa Trenes Argentinos ha puesto en marcha un nuevo cronograma de horarios para el Tren de la Costa, que recorre 15 kil\u00f3metros a lo largo del norte del Conurbano, en paralelo al R\u00edo de la Plata y la Avenida Libertador. Este servicio, que conecta la estaci\u00f3n Maip\u00fa, frente a la Quinta Presidencial de Olivos, con la estaci\u00f3n Delta, ubicada frente al Casino de Tigre, busca mejorar la experiencia de viaje de sus usuarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/03\/TREN-COSTA-3-1024x576-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"597\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/03\/TREN-COSTA-3-1024x576-1-1024x597.jpg\" alt=\"\" class=\"wp-image-21277\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/03\/TREN-COSTA-3-1024x576-1-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/03\/TREN-COSTA-3-1024x576-1-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/03\/TREN-COSTA-3-1024x576-1-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/03\/TREN-COSTA-3-1024x576-1.jpg 1200w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><figcaption class=\"wp-element-caption\"><strong>Vista a\u00e9rea del Tren de la Costa que une la estaci\u00f3n Maip\u00fa, frente a la Quinta Presidencial, con la estaci\u00f3n Delta, pegada al casino tigrense<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El nuevo diagrama de horarios comenz\u00f3 a regir desde anteayer. Ahora, el \u00faltimo tren que parte desde la estaci\u00f3n Maip\u00fa saldr\u00e1 a las 22:50, una mejora significativa respecto a la anterior salida a las 21:20. Por su parte, desde la estaci\u00f3n Delta, el \u00faltimo tren partir\u00e1 a las 22:20, en lugar de las 20:50. Aunque se han ajustado los horarios, la empresa ha aclarado que no se incorporar\u00e1n nuevas frecuencias; los \u00faltimos servicios del d\u00eda ahora circular\u00e1n cada 30 minutos, en vez de cada 20.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos cambios responden a un an\u00e1lisis del flujo de pasajeros, que suele incrementarse con el fin del verano y el regreso a la rutina habitual, permitiendo as\u00ed un mejor aprovechamiento del servicio durante el resto del a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-jetpack-related-posts\">\n<h4 class=\"wp-block-heading\">Noticias relacionadas<\/h4>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">M\u00e1s noticias<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<ul class=\"wp-block-latest-posts__list is-grid columns-2 has-author aligncenter wp-block-latest-posts\"><li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/benavidez-detencion-narcomenudeo-operativo-cot\/\" aria-label=\"Detuvieron a dos personas por comercializar drogas en Benav\u00eddez\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"295\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot8-1024x576.png\" class=\"attachment-large size-large wp-post-image\" alt=\"Dispositivo de seguridad y patrullas del COT interviniendo en la detenci\u00f3n de los implicados en Benav\u00eddez\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot8-1024x576.png 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot8-300x169.png 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot8-768x432.png 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot8.png 1280w\" sizes=\"auto, 100vw\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/benavidez-detencion-narcomenudeo-operativo-cot\/\">Detuvieron a dos personas por comercializar drogas en Benav\u00eddez<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/rincon-de-milberg-jardin-950-entrega-material-ludico\/\" aria-label=\"El Municipio entreg\u00f3 nuevos kits did\u00e1cticos en el Jard\u00edn N\u00b0950 de Rinc\u00f3n de Milberg\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-11-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Integrantes del equipo educativo y autoridades locales durante la presentaci\u00f3n de los nuevos kits de juego en el Jard\u00edn N\u00b0950 de Rinc\u00f3n de Milberg\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-11-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-11-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-11-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-11.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/rincon-de-milberg-jardin-950-entrega-material-ludico\/\">El Municipio entreg\u00f3 nuevos kits did\u00e1cticos en el Jard\u00edn N\u00b0950 de Rinc\u00f3n de Milberg<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/inauguracion-nuevos-vestuarios-polideportivo-delfo-cabrera-el-talar\/\" aria-label=\"El Talar: quedaron inaugurados los vestuarios del Polideportivo municipal Delfo Cabrera\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot1-1-1024x597.png\" class=\"attachment-large size-large wp-post-image\" alt=\"Se construyeron dos vestuarios principales para hombres y mujeres. Incluye cambiadores para ni\u00f1os pensados para actividades infantiles, ba\u00f1os para personas con discapacidad, sectores de apoyo y un sector para revisiones m\u00e9dicas\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot1-1-1024x597.png 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot1-1-300x175.png 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot1-1-768x448.png 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot1-1.png 1200w\" sizes=\"auto, 100vw\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/inauguracion-nuevos-vestuarios-polideportivo-delfo-cabrera-el-talar\/\">El Talar: quedaron inaugurados los vestuarios del Polideportivo municipal Delfo Cabrera<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/entrega-certificados-emprendedoras-rodantes-tigre\/\" aria-label=\"M\u00e1s de 100 vecinas de Tigre recibieron sus certificados del programa Emprendedoras Rodantes\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-4-3-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Vecinas de Tigre exhiben sus diplomas de finalizaci\u00f3n de talleres junto a sus kits de trabajo en el Centro Universitario\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-4-3-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-4-3-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-4-3-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-4-3.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/entrega-certificados-emprendedoras-rodantes-tigre\/\">M\u00e1s de 100 vecinas de Tigre recibieron sus certificados del programa Emprendedoras Rodantes<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/puesta-valor-polideportivo-tercera-edad-rincon-milberg\/\" aria-label=\"Finalizaron obras de infraestructura en el predio para la tercera edad Ecosol\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-3-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Adultos mayores celebraron el 9 de Julio en las instalaciones renovadas del polideportivo municipal\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-3-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-3-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-3-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-3.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/puesta-valor-polideportivo-tercera-edad-rincon-milberg\/\">Finalizaron obras de infraestructura en el predio para la tercera edad Ecosol<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/siniestro-vial-auto-moto-benavidez-camino-bota\/\" aria-label=\"Maniobra imprudente en Benav\u00eddez provoca violento choque\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"295\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot10.png\" class=\"attachment-large size-large wp-post-image\" alt=\"El choque ocurri\u00f3 a primera hora de la ma\u00f1ana, cuando el rodado de mayor porte colision\u00f3 de frente al motoveh\u00edculo que circulaba por Colectora Este -en sentido opuesto- y su intersecci\u00f3n con Camino de la Bota. Al detectar lo ocurrido a trav\u00e9s de las c\u00e1maras, los operadores de la central dieron aviso al m\u00f3vil m\u00e1s cercano.\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot10.png 640w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot10-300x169.png 300w\" sizes=\"auto, 100vw\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/siniestro-vial-auto-moto-benavidez-camino-bota\/\">Maniobra imprudente en Benav\u00eddez provoca violento choque<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/agenda-actividades-gratuitas-vacaciones-invierno-tigre\/\" aria-label=\"El Municipio de Tigre present\u00f3 sus propuestas culturales gratuitas para las vacaciones de invierno\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-6-1-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Con m\u00e1s de 70 propuestas culturales para las vacaciones de invierno, el Municipio ofrecer\u00e1 una amplia agenda gratuita de espect\u00e1culos, teatro, cine\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-6-1-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-6-1-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-6-1-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-6-1.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/agenda-actividades-gratuitas-vacaciones-invierno-tigre\/\">El Municipio de Tigre present\u00f3 sus propuestas culturales gratuitas para las vacaciones de invierno<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/vecinos-troncos-talar-celebraron-dia-independencia\/\" aria-label=\"La comunidad de Troncos del Talar celebr\u00f3 el 9 de Julio junto a autoridades municipales\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-2-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"El intendente Julio Zamora particip\u00f3 del encuentro con la comunidad en la Asociaci\u00f3n Junta Vecinal.\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-2-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-2-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-2-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-2.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/vecinos-troncos-talar-celebraron-dia-independencia\/\">La comunidad de Troncos del Talar celebr\u00f3 el 9 de Julio junto a autoridades municipales<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/entrega-anteojos-programa-para-verte-mejor-tigre\/\" aria-label=\"\u00abPara Verte Mejor\u00bb alcanz\u00f3 los 500 pares de anteojos entregados a estudiantes durante el primer semestre\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-7-1-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"La secretaria de Educaci\u00f3n y Promoci\u00f3n Social, Gisela Zamora, particip\u00f3 de una nueva jornada del programa municipal de salud visual\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-7-1-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-7-1-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-7-1-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-7-1.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/entrega-anteojos-programa-para-verte-mejor-tigre\/\">\u00abPara Verte Mejor\u00bb alcanz\u00f3 los 500 pares de anteojos entregados a estudiantes durante el primer semestre<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/talleres-orientacion-vocacional-centro-universitario-tigre\/\" aria-label=\"Estudiantes secundarios participaron de una nueva jornada de orientaci\u00f3n vocacional en el CUT\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-1-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"El Municipio llev\u00f3 a cabo una nueva jornada del Taller de Orientaci\u00f3n Vocacional en el Centro Universitario Tigre (CUT). Los estudiantes de sexto a\u00f1o de secundaria participaron de una recorrida por el espacio y se presentaron las ofertas acad\u00e9micas locales\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-1-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-1-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-1-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-1.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/talleres-orientacion-vocacional-centro-universitario-tigre\/\">Estudiantes secundarios participaron de una nueva jornada de orientaci\u00f3n vocacional en el CUT<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<\/ul>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-cover is-light\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"500\" class=\"wp-block-cover__image-background wp-image-18331\" alt=\"\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2023\/11\/LOGO-TIGRE-DIGITAL-CIRCULO.png\" data-object-fit=\"cover\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2023\/11\/LOGO-TIGRE-DIGITAL-CIRCULO.png 480w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2023\/11\/LOGO-TIGRE-DIGITAL-CIRCULO-288x300.png 288w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-group alignfull has-background-color has-white-color has-black-background-color has-text-color has-background has-link-color wp-elements-37ea6134c40452122b721bb912a37805\" style=\"min-height:40vh;margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--60);padding-right:var(--wp--preset--spacing--40);padding-bottom:var(--wp--preset--spacing--60);padding-left:var(--wp--preset--spacing--40)\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-container-core-group-is-layout-73ba516b wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns alignwide has-small-font-size is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center wp-block-paragraph\">(1648) Tigre<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Buenos Aires<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Argentina<\/p>\n\n\n\n<div style=\"height:24px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-stretch is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center wp-block-paragraph\">Comunicate con nosotros:<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><a href=\"contacto@tigredigital.com.ar\" target=\"_blank\" rel=\"noreferrer noopener\">contacto@tigredigital.com.ar<\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/tigredigital.com.ar\/noticias\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"500\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2023\/11\/LOGO-TIGRE-DIGITAL-CIRCULO-1.png\" alt=\"\" class=\"wp-image-18332\" style=\"width:98px;height:auto\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2023\/11\/LOGO-TIGRE-DIGITAL-CIRCULO-1.png 480w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2023\/11\/LOGO-TIGRE-DIGITAL-CIRCULO-1-288x300.png 288w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><\/figure>\n<\/div>\n\n\n<div style=\"height:24px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center wp-block-paragraph\">Adem\u00e1s pod\u00e9s  seguirnos en<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">nuestras redes sociales:<\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-center is-layout-flex wp-container-core-group-is-layout-35affd85 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/tigredigital\/\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.instagram.com\/tigredigitalnoticias\/\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/twitter.com\/digital_tigre\" target=\"_blank\" rel=\"noreferrer noopener\">Twitter<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.youtube.com\/channel\/UC26DeuIB96yC2vbePmuFH5A\" target=\"_blank\" rel=\"noreferrer noopener\">Youtube<\/a><\/p>\n<\/div>\n\n\n\n<div style=\"height:24px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center has-small-font-size wp-block-paragraph\">Proudly powered by <a href=\"https:\/\/wordpress.org\" rel=\"nofollow noopener\" target=\"_blank\">WordPress<\/a> <\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A partir de esta semana, la empresa Trenes Argentinos ha puesto en marcha un nuevo cronograma de horarios para el Tren de la Costa, que recorre 15 kil\u00f3metros a lo largo del norte del Conurbano, en paralelo al R\u00edo de la Plata y la Avenida Libertador. Este servicio, que conecta la estaci\u00f3n Maip\u00fa, frente a la Quinta Presidencial de Olivos, con la estaci\u00f3n Delta, ubicada frente al Casino de Tigre, busca mejorar la experiencia de viaje de sus usuarios.<\/p>\n","protected":false},"author":2,"featured_media":21278,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[50],"tags":[941,65,940],"class_list":["post-21276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servicios-publicos","tag-horarios","tag-tigre","tag-tren-de-la-costa"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/03\/FotoJet-2025-03-11T182940.431.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":22314,"url":"https:\/\/tigredigital.com.ar\/noticias\/el-ramal-tigre-del-mitre-estara-interrumpido-por-nueve-dias\/","url_meta":{"origin":21276,"position":0},"title":"El\u00a0ramal Tigre del tren Mitre\u00a0estar\u00e1 interrumpido por nueve d\u00edas","author":"Daniel Lowy","date":"31 julio, 2025","format":false,"excerpt":"De acuerdo a lo informado por\u00a0Trenes Argentinos\u00a0en la cuenta oficial de la l\u00ednea ferroviaria,\u00a0el ramal Tigre del tren Mitre\u00a0no funcionar\u00e1 a partir del s\u00e1bado 9 de agosto. Inicialmente, la suspensi\u00f3n del servicio se iba a llevar a cabo entre el s\u00e1bado 19 y el domingo 27 de julio, en coincidencia\u2026","rel":"","context":"En \u00abInformaci\u00f3n General\u00bb","block_context":{"text":"Informaci\u00f3n General","link":"https:\/\/tigredigital.com.ar\/noticias\/category\/informacion-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/07\/obra-linea-mitre.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/07\/obra-linea-mitre.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/07\/obra-linea-mitre.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/07\/obra-linea-mitre.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/07\/obra-linea-mitre.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":22610,"url":"https:\/\/tigredigital.com.ar\/noticias\/futuro-incierto-para-el-iconico-parque-de-la-costa\/","url_meta":{"origin":21276,"position":1},"title":"Futuro incierto para el ic\u00f3nico Parque de la Costa","author":"Daniel Lowy","date":"11 septiembre, 2025","format":false,"excerpt":"Futuro incierto para el ic\u00f3nico Parque de la Costa La situaci\u00f3n de incertidumbre surge luego de que una resoluci\u00f3n del Gobierno Nacional desafectara del uso ferroviario un predio de m\u00e1s de 50 mil metros cuadrados en Tigre en donde actualmente tiene su espacio el parque de diversiones y que deja\u2026","rel":"","context":"En \u00abInformaci\u00f3n General\u00bb","block_context":{"text":"Informaci\u00f3n General","link":"https:\/\/tigredigital.com.ar\/noticias\/category\/informacion-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/09\/parque-de-la-costa.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/09\/parque-de-la-costa.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/09\/parque-de-la-costa.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/09\/parque-de-la-costa.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/09\/parque-de-la-costa.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":23482,"url":"https:\/\/tigredigital.com.ar\/noticias\/tren-mitre-ramal-tigre-vuelta-servicio-retiro-1-marzo\/","url_meta":{"origin":21276,"position":2},"title":"Tren Mitre: Hay fecha confirmada para la normalizaci\u00f3n del servicio","author":"Daniel Lowy","date":"24 febrero, 2026","format":false,"excerpt":"Los usuarios del Tren Mitre ramal Tigre ya tienen una fecha marcada en el calendario para el regreso a la normalidad. Seg\u00fan confirmaron desde Trenes Argentinos, el pr\u00f3ximo 1 de marzo se restablecer\u00e1 el servicio completo entre las estaciones de Tigre y Retiro, poniendo fin a la interrupci\u00f3n que comenz\u00f3\u2026","rel":"","context":"En \u00abServicios p\u00fablicos\u00bb","block_context":{"text":"Servicios p\u00fablicos","link":"https:\/\/tigredigital.com.ar\/noticias\/category\/servicios-publicos\/"},"img":{"alt_text":"Hay fecha para el regreso del Tren Mitre a Tigre","src":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/02\/LINEA-MITRE-ESTACION-TIGRE.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/02\/LINEA-MITRE-ESTACION-TIGRE.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/02\/LINEA-MITRE-ESTACION-TIGRE.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/02\/LINEA-MITRE-ESTACION-TIGRE.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/02\/LINEA-MITRE-ESTACION-TIGRE.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":21910,"url":"https:\/\/tigredigital.com.ar\/noticias\/tigre-promovio-la-vacunacion-contra-el-sarampion-con-una-jornada-en-el-centro-de-la-ciudad\/","url_meta":{"origin":21276,"position":3},"title":"Tigre promovi\u00f3 la vacunaci\u00f3n contra el sarampi\u00f3n con una jornada en el centro de la ciudad","author":"Daniel Lowy","date":"4 junio, 2025","format":false,"excerpt":"Bajo el lema \"La tarde de las vacunas\", el Municipio realiz\u00f3 una jornada extensiva de vacunaci\u00f3n contra el sarampi\u00f3n destinada a ni\u00f1os y ni\u00f1as. Fue en la estaci\u00f3n de trenes de Tigre, donde personal de la gesti\u00f3n local brind\u00f3 las dosis de forma gratuita.","rel":"","context":"En \u00abSalud\u00bb","block_context":{"text":"Salud","link":"https:\/\/tigredigital.com.ar\/noticias\/category\/salud\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/06\/unnamed-1-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/06\/unnamed-1-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/06\/unnamed-1-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/06\/unnamed-1-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2025\/06\/unnamed-1-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":18745,"url":"https:\/\/tigredigital.com.ar\/noticias\/descarrilo-una-formacion-del-tren-mitre-a-metros-de-la-estacion-tigre\/","url_meta":{"origin":21276,"position":4},"title":"Descarril\u00f3 una formaci\u00f3n del tren Mitre a metros de la estaci\u00f3n Tigre","author":"Daniel Lowy","date":"26 febrero, 2024","format":false,"excerpt":"El hecho se produjo en horas de la ma\u00f1ana en momentos en que la formaci\u00f3n abandonaba la estaci\u00f3n con direcci\u00f3n a Retiro. No hubo que lamentar heridos Una formaci\u00f3n de la\u00a0L\u00ednea Mitre\u00a0de trenes descarril\u00f3 a metros de la estaci\u00f3n\u00a0Tigre\u00a0cuando intentaba cambiar de v\u00eda. Uno de los vagones se descalz\u00f3 y\u2026","rel":"","context":"En \u00abInformaci\u00f3n General\u00bb","block_context":{"text":"Informaci\u00f3n General","link":"https:\/\/tigredigital.com.ar\/noticias\/category\/informacion-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-26-at-15.36.37-2.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-26-at-15.36.37-2.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-26-at-15.36.37-2.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-26-at-15.36.37-2.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-26-at-15.36.37-2.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":13370,"url":"https:\/\/tigredigital.com.ar\/noticias\/por-el-dia-mundial-del-agua-aysa-realizara-un-flashmob-en-la-estacion-de-trenes\/","url_meta":{"origin":21276,"position":5},"title":"Por el D\u00eda Mundial del Agua, AySA realizar\u00e1 un \u00abflashmob\u00bb en la Estaci\u00f3n de Trenes","author":"Daniel Ernesto Lowy","date":"22 marzo, 2022","format":false,"excerpt":"Ser\u00e1 este mi\u00e9rcoles 23 durante el regreso a casa de los usuarios la l\u00ednea Mitre En conmemoraci\u00f3n del D\u00eda Mundial del Agua, la empresa que preside Malena Galmarini,\u00a0AySA, se har\u00e1 presente en la terminal de la L\u00ednea Mitre, con un baile colectivo buscando concientizar al p\u00fablico sobre el cuidado de\u2026","rel":"","context":"En \u00abInformaci\u00f3n General\u00bb","block_context":{"text":"Informaci\u00f3n General","link":"https:\/\/tigredigital.com.ar\/noticias\/category\/informacion-general\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2022\/03\/03-22_dia_mundial_del_agua_slider2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2022\/03\/03-22_dia_mundial_del_agua_slider2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2022\/03\/03-22_dia_mundial_del_agua_slider2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2022\/03\/03-22_dia_mundial_del_agua_slider2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2022\/03\/03-22_dia_mundial_del_agua_slider2.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/21276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=21276"}],"version-history":[{"count":1,"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/21276\/revisions"}],"predecessor-version":[{"id":21279,"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/21276\/revisions\/21279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/21278"}],"wp:attachment":[{"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=21276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=21276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=21276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}