{"id":17412,"date":"2023-05-31T10:43:36","date_gmt":"2023-05-31T13:43:36","guid":{"rendered":"https:\/\/tigredigital.com.ar\/noticias\/?p=17412"},"modified":"2023-05-31T10:43:38","modified_gmt":"2023-05-31T13:43:38","slug":"perdio-el-control-de-su-vehiculo-e-impacto-contra-un-comercio-en-tigre-centro","status":"publish","type":"post","link":"https:\/\/tigredigital.com.ar\/noticias\/perdio-el-control-de-su-vehiculo-e-impacto-contra-un-comercio-en-tigre-centro\/","title":{"rendered":"Perdi\u00f3 el control de su veh\u00edculo e impact\u00f3 contra un comercio en Tigre centro"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Las c\u00e1maras del Municipio de Tigre captaron un impactante accidente de tr\u00e1nsito en el centro de la ciudad e inmediatamente el Sistema de Protecci\u00f3n Ciudadana mont\u00f3 un operativo para brindar asistencia<\/strong><\/p>\n\n\n\n<!--more-->\n<!--noteaser-->\n\n\n\n<p class=\"wp-block-paragraph\">Las c\u00e1maras del Municipio de Tigre captaron un impactante accidente de tr\u00e1nsito en el centro de la ciudad e inmediatamente el Sistema de Protecci\u00f3n Ciudadana mont\u00f3 un operativo para brindar asistencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todo comenz\u00f3 cuando un veh\u00edculo que circulaba por Av. Caz\u00f3n perdi\u00f3 el control e impact\u00f3 contra un comercio. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Perdi\u00f3 el control de su veh\u00edculo e impact\u00f3 contra un comercio en Tigre centro\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/LuZrtzSVC0o?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras alertar peligro por fuga de gas, acudieron r\u00e1pidamente al lugar los m\u00f3viles del COT que patrullaban la zona, Bomberos voluntarios de la localidad y personal del SET, Defensa Civil y Tr\u00e1nsito. Afortunadamente, los ocupantes del veh\u00edculo no presentaron heridas de gravedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<ul class=\"wp-block-latest-posts__list has-author wp-block-latest-posts\"><li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-11-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Integrantes del equipo educativo y autoridades locales durante la presentaci\u00f3n de los nuevos kits de juego en el Jard\u00edn N\u00b0950 de Rinc\u00f3n de Milberg\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-11-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-11-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-11-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-11.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/rincon-de-milberg-jardin-950-entrega-material-ludico\/\">El Municipio entreg\u00f3 nuevos kits did\u00e1cticos en el Jard\u00edn N\u00b0950 de Rinc\u00f3n de Milberg<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot1-1-1024x597.png\" class=\"attachment-large size-large wp-post-image\" alt=\"Se construyeron dos vestuarios principales para hombres y mujeres. Incluye cambiadores para ni\u00f1os pensados para actividades infantiles, ba\u00f1os para personas con discapacidad, sectores de apoyo y un sector para revisiones m\u00e9dicas\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot1-1-1024x597.png 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot1-1-300x175.png 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot1-1-768x448.png 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot1-1.png 1200w\" sizes=\"auto, 100vw\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/inauguracion-nuevos-vestuarios-polideportivo-delfo-cabrera-el-talar\/\">El Talar: quedaron inaugurados los vestuarios del Polideportivo municipal Delfo Cabrera<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-4-3-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Vecinas de Tigre exhiben sus diplomas de finalizaci\u00f3n de talleres junto a sus kits de trabajo en el Centro Universitario\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-4-3-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-4-3-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-4-3-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-4-3.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/entrega-certificados-emprendedoras-rodantes-tigre\/\">M\u00e1s de 100 vecinas de Tigre recibieron sus certificados del programa Emprendedoras Rodantes<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-3-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Adultos mayores celebraron el 9 de Julio en las instalaciones renovadas del polideportivo municipal\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-3-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-3-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-3-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-3.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/puesta-valor-polideportivo-tercera-edad-rincon-milberg\/\">Finalizaron obras de infraestructura en el predio para la tercera edad Ecosol<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"295\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot10.png\" class=\"attachment-large size-large wp-post-image\" alt=\"El choque ocurri\u00f3 a primera hora de la ma\u00f1ana, cuando el rodado de mayor porte colision\u00f3 de frente al motoveh\u00edculo que circulaba por Colectora Este -en sentido opuesto- y su intersecci\u00f3n con Camino de la Bota. Al detectar lo ocurrido a trav\u00e9s de las c\u00e1maras, los operadores de la central dieron aviso al m\u00f3vil m\u00e1s cercano.\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot10.png 640w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/snapshot10-300x169.png 300w\" sizes=\"auto, 100vw\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/siniestro-vial-auto-moto-benavidez-camino-bota\/\">Maniobra imprudente en Benav\u00eddez provoca violento choque<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-6-1-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Con m\u00e1s de 70 propuestas culturales para las vacaciones de invierno, el Municipio ofrecer\u00e1 una amplia agenda gratuita de espect\u00e1culos, teatro, cine\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-6-1-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-6-1-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-6-1-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-6-1.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/agenda-actividades-gratuitas-vacaciones-invierno-tigre\/\">El Municipio de Tigre present\u00f3 sus propuestas culturales gratuitas para las vacaciones de invierno<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-2-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"El intendente Julio Zamora particip\u00f3 del encuentro con la comunidad en la Asociaci\u00f3n Junta Vecinal.\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-2-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-2-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-2-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-2.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/vecinos-troncos-talar-celebraron-dia-independencia\/\">La comunidad de Troncos del Talar celebr\u00f3 el 9 de Julio junto a autoridades municipales<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-7-1-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"La secretaria de Educaci\u00f3n y Promoci\u00f3n Social, Gisela Zamora, particip\u00f3 de una nueva jornada del programa municipal de salud visual\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-7-1-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-7-1-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-7-1-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-7-1.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/entrega-anteojos-programa-para-verte-mejor-tigre\/\">\u00abPara Verte Mejor\u00bb alcanz\u00f3 los 500 pares de anteojos entregados a estudiantes durante el primer semestre<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-1-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"El Municipio llev\u00f3 a cabo una nueva jornada del Taller de Orientaci\u00f3n Vocacional en el Centro Universitario Tigre (CUT). Los estudiantes de sexto a\u00f1o de secundaria participaron de una recorrida por el espacio y se presentaron las ofertas acad\u00e9micas locales\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-1-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-1-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-1-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-1-1.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/talleres-orientacion-vocacional-centro-universitario-tigre\/\">Estudiantes secundarios participaron de una nueva jornada de orientaci\u00f3n vocacional en el CUT<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"306\" src=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-5-1-1024x597.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"El intendente Julio Zamora particip\u00f3 del plenario organizado por la UES en General Pacheco.\" style=\"\" srcset=\"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-5-1-1024x597.jpg 1024w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-5-1-300x175.jpg 300w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-5-1-768x448.jpg 768w, https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2026\/07\/unnamed-5-1.jpg 1200w\" sizes=\"auto, 100vw\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/tigredigital.com.ar\/noticias\/plenario-centros-estudiantes-tigre-sala-aparecidas\/\">Estudiantes secundarios de Tigre realizaron un plenario para debatir problem\u00e1ticas escolares<\/a><div class=\"wp-block-latest-posts__post-author\">por Daniel Lowy<\/div><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Las c\u00e1maras del Municipio de Tigre captaron un impactante accidente de tr\u00e1nsito en el centro de la ciudad e inmediatamente el Sistema de Protecci\u00f3n Ciudadana mont\u00f3 un operativo para brindar asistencia<\/p>\n","protected":false},"author":2,"featured_media":17413,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[13],"tags":[71,65],"class_list":["post-17412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales","tag-policiales","tag-tigre"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/tigredigital.com.ar\/noticias\/wp-content\/uploads\/2023\/05\/7c62b866e7ed5037c3956fadbfb20037e216effbfe63840beb3801ca5569421e.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/17412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=17412"}],"version-history":[{"count":1,"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/17412\/revisions"}],"predecessor-version":[{"id":17414,"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/17412\/revisions\/17414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/17413"}],"wp:attachment":[{"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=17412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=17412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tigredigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=17412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}